{"id":6797,"date":"2026-09-02T09:00:00","date_gmt":"2026-09-02T08:00:00","guid":{"rendered":"https:\/\/visaeta.uk\/?p=6797"},"modified":"2026-08-28T05:00:10","modified_gmt":"2026-08-28T04:00:10","slug":"cancel-visa-application-uk-2026","status":"publish","type":"post","link":"https:\/\/visaeta.uk\/de\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/","title":{"rendered":"So k\u00fcndigen oder widerrufen Sie einen UK-Visumantrag (2026)"},"content":{"rendered":"<p><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"627\" src=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061949.jpg\" alt=\"Person storniert einen UK-Visumantrag auf einem Laptop mit Pass in der N\u00e4he\" class=\"wp-image-6791\" srcset=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061949.jpg 940w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061949-300x200.jpg 300w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061949-768x512.jpg 768w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061949-18x12.jpg 18w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/figure>\n<\/p>\n<p><strong>Sie k\u00f6nnen eine Visumbeantragung, die UK-Antragsteller begonnen haben, fast jederzeit vor einer Entscheidung stornieren, aber das, was Sie zur\u00fcckbekommen, h\u00e4ngt vom Zeitpunkt ab.<\/strong> Ziehen Sie sich vor der Bezahlung zur\u00fcck und es geht nichts verloren. Ziehen Sie sich nach dem Absenden und der Bezahlung zur\u00fcck, und die Visumgeb\u00fchr ist weg \u2013 obwohl ein ungenutzter biometrischer Slot oder ein Kurier-Add-on manchmal erstattet werden kann. Diese Anleitung f\u00fchrt Sie durch die genauen Schritte, die finanzielle Seite und wie Sie sich sauber neu bewerben.<\/p>\n<p><strong>Kurz gesagt:<\/strong> Um eine Visaanwendung zu stornieren, m\u00fcssen britische Reisende diese vor der Biometrie \u00fcber ihr UKVI- oder Gesch\u00e4ftspartnerkonto (TLScontact oder VFS Global) zur\u00fcckziehen. Die Hauptvisumgeb\u00fchr ist nach Einreichung nicht erstattungsf\u00e4hig, aber die Immigration Health Surcharge und einige optionale Dienstleistungen werden automatisch erstattet. Eine erneute Beantragung ist sofort mit einem neuen Formular und einer neuen Zahlung m\u00f6glich.<\/p>\n<table>\n<thead>\n<tr>\n<th>Schnelle Fakten<\/th>\n<th>Einzelheiten<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Wo man stornieren kann<\/td>\n<td>UKVI \/ TLScontact \/ VFS Global Konto<\/td>\n<\/tr>\n<tr>\n<td>Visumgeb\u00fchr erstattungsf\u00e4hig?<\/td>\n<td>Nein, sobald die Anwendung eingereicht ist<\/td>\n<\/tr>\n<tr>\n<td>IHS erstattungsf\u00e4hig?<\/td>\n<td>Ja \u2014 automatisch erstattet, wenn das Visum widerrufen oder abgelehnt wird<\/td>\n<\/tr>\n<tr>\n<td>Nach Stornierung erneut beantragen?<\/td>\n<td>Ja, sofort, mit einer neuen Anwendung und Geb\u00fchr<\/td>\n<\/tr>\n<tr>\n<td>Standardentscheidungszeit<\/td>\n<td>Etwa 3 Wochen f\u00fcr ein Standard Visitor Visa<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Pl\u00e4ne \u00e4ndern sich. Vielleicht ist Ihre Reise in die Br\u00fcche gegangen, vielleicht haben Sie einen Fehler im Formular bemerkt, oder vielleicht haben Sie einfach die falsche Visumroute gew\u00e4hlt. Was auch immer der Grund ist, Sie sind nicht an einen Antrag gebunden, den Sie nicht mehr wollen. Nachfolgend erfahren Sie, was tats\u00e4chlich passiert, wenn Sie den Stecker ziehen, und wie Sie Ihr Geld sch\u00fctzen. Wenn Sie die Route selbst noch abw\u00e4gen, ist unser <a href=\"https:\/\/visaeta.uk\/de\/blog\/applying-for-a-standard-visitor-visa-to-the-uk-a-step-by-step-guide\/\">Schritt-f\u00fcr-Schritt-Leitfaden f\u00fcr Standard Visitor Visa<\/a> ist ein guter Ausgangspunkt.<\/p>\n<h2>K\u00f6nnen Sie UK-Visaantragsformulare nach dem Einreichen stornieren?<\/h2>\n<p><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"627\" src=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-33497885.jpg\" alt=\"UK-Visumantrag und Pass auf einem Holzschreibtisch\" class=\"wp-image-6792\" srcset=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-33497885.jpg 940w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-33497885-300x200.jpg 300w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-33497885-768x512.jpg 768w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-33497885-18x12.jpg 18w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/figure>\n<\/p>\n<p><strong>Ja \u2013 Sie k\u00f6nnen UK-Visaantragsformulare nach dem Einreichen stornieren, aber die Hauptvisageb\u00fchr wird nicht erstattet.<\/strong> UK Visas and Immigration behandelt die Geb\u00fchr als Zahlung f\u00fcr die Bearbeitung, und die Bearbeitung beginnt in dem Moment, in dem Sie den Antrag einreichen. Ziehen Sie sich vor der Zahlung zur\u00fcck, schulden Sie nichts. Ziehen Sie sich nach der Zahlung, aber vor der Biometrie zur\u00fcck, verfallen Sie die Visageb\u00fchr, behalten aber alle r\u00fcckerstattbaren Zusatzleistungen. The <a href=\"https:\/\/www.gov.uk\/visa-fees\" target=\"_blank\" rel=\"noopener\">offizielle UK-Visageb\u00fchrenseite<\/a> (gov.uk, abgerufen am 1. Juli 2026) best\u00e4tigt, dass Geb\u00fchren pro Antrag und nicht pro Ergebnis erhoben werden.<\/p>\n<p>Es gibt einen Lichtblick. Die Immigration Health Surcharge \u2013 oft die gr\u00f6\u00dfte einzelne Position bei einem Langzeitantrag \u2013 wird automatisch erstattet, wenn ein Antrag zur\u00fcckgezogen oder abgelehnt wird. The <a href=\"https:\/\/www.gov.uk\/apply-to-come-to-the-uk\" target=\"_blank\" rel=\"noopener\">UKVI-Anwendungsportal<\/a> Prozesse, die auf Ihre urspr\u00fcngliche Karte zur\u00fcckerstattet werden, normalerweise innerhalb weniger Wochen. Kurzfristige Besuchervisa beinhalten nicht die Zusatzgeb\u00fchr, daher hilft dies haupts\u00e4chlich Arbeits- und Studienantragstellern.<\/p>\n<blockquote>\n<p><strong>Profi-Tipp:<\/strong> Brechen Sie nicht ab, nur weil Sie einen kleinen Fehler bemerkt haben. Viele Fehler \u2013 ein Tippfehler in einer Adresse, eine falsche Telefonnummer \u2013 k\u00f6nnen bei Ihrem biometrischen Termin oder durch Kontaktaufnahme mit dem Visumzentrum korrigiert werden. Das Abbrechen und Neustarten kostet Sie die gesamte Geb\u00fchr erneut.<\/p>\n<\/blockquote>\n<h2>Wie man einen UK-Visumantrag Schritt f\u00fcr Schritt widerruft<\/h2>\n<p><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"627\" src=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061944.jpg\" alt=\"Reisender \u00fcberpr\u00fcft Schritte zum R\u00fcckzug eines UK-Visaantrags auf einem Telefon\" class=\"wp-image-6793\" srcset=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061944.jpg 940w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061944-300x200.jpg 300w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061944-768x512.jpg 768w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061944-18x12.jpg 18w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/figure>\n<\/p>\n<p><strong>Um zu widerrufen, melden Sie sich bei dem Konto an, das Sie f\u00fcr die Bewerbung verwendet haben, \u00f6ffnen Sie die ausstehende Anwendung und w\u00e4hlen Sie die Widerrufsoption \u2013 die meisten K\u00fcndigungen dauern weniger als zehn Minuten.<\/strong> Die genaue Schaltfl\u00e4che h\u00e4ngt davon ab, wo Sie sich beworben haben. Antragsteller au\u00dferhalb des Vereinigten K\u00f6nigreichs nutzen normalerweise TLScontact oder VFS Global; Antragsteller im Vereinigten K\u00f6nigreich nutzen den UKVI-Online-Service. Wenn Sie die Option nicht finden k\u00f6nnen, wenden Sie sich direkt an UK Visas and Immigration.<\/p>\n<ol>\n<li><strong>Melden Sie sich an<\/strong> in Ihr UKVI-, TLScontact- oder VFS Global-Konto mit der E-Mail, mit der Sie sich registriert haben.<\/li>\n<li><strong>\u00d6ffnen Sie die aktive Anwendung<\/strong> und \u00fcberpr\u00fcfen Sie seinen Status. Wenn er bereits &#8220;in Bearbeitung&#8221; bei einem Entscheidungszentrum angezeigt wird, kann ein Widerruf ihn m\u00f6glicherweise nicht mehr stoppen.<\/li>\n<li><strong>W\u00e4hlen Sie &#8220;R\u00fccknahme&#8221; oder &#8220;Stornierung&#8221;<\/strong> und best\u00e4tigen Sie. Machen Sie einen Screenshot des Best\u00e4tigungsbildschirms.<\/li>\n<li><strong>Stornieren Sie Ihren Biometrischen Termin<\/strong> separat, wenn das System dies nicht f\u00fcr Sie tut.<\/li>\n<li><strong>Warten Sie auf die Best\u00e4tigungs-E-Mail.<\/strong> Bewahren Sie diese auf \u2013 m\u00f6glicherweise ben\u00f6tigen Sie einen Nachweis der R\u00fccknahme, wenn Sie erneut einen Antrag stellen.<\/li>\n<\/ol>\n<p>Wenn keine Self-Service-Option angezeigt wird, verwenden Sie die <a href=\"https:\/\/www.gov.uk\/contact-ukvi-inside-outside-uk\" target=\"_blank\" rel=\"noopener\">offizielle UKVI-Kontaktseite<\/a> (gov.uk, abgerufen am 1. Juli 2026) um eine R\u00fccknahme per E-Mail oder Telefon anzufordern. Geben Sie Ihre GWF- oder Antragsreferenznummer in der ersten Zeile an \u2013 das beschleunigt den Prozess. F\u00fcr Bearbeitungszeiten, die beeinflussen, ob eine R\u00fccknahme noch m\u00f6glich ist, siehe unseren Leitfaden zu <a href=\"https:\/\/visaeta.uk\/de\/blog\/how-long-does-uk-visa-processing-take-a-detailed-guide\/\">wie lange die UK-Visumbearbeitung dauert<\/a>.<\/p>\n<h2>Was geschieht mit Ihrem Geld und Ihren Geb\u00fchren<\/h2>\n<p><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"627\" src=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061986.jpg\" alt=\"Bankkarte und Unterlagen zeigen UK-Visumgeb\u00fchren unter \u00dcberpr\u00fcfung\" class=\"wp-image-6794\" srcset=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061986.jpg 940w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061986-300x200.jpg 300w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061986-768x512.jpg 768w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061986-18x12.jpg 18w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/figure>\n<\/p>\n<p><strong>Nach Einreichung ist die Visumgeb\u00fchr nicht erstattbar, aber die Gesundheitsgeb\u00fchr und einige optionale Dienstleistungen werden zur\u00fcckgegeben.<\/strong> Das ist der Teil, der die Leute verwirrt. Eine Visumgeb\u00fchr f\u00fcr ein sechsmonatiges Standard Visitor Visum \u2014 aufgelistet mit \u00a3127 in der Geb\u00fchrentabelle, die nach der Erh\u00f6hung vom 9. April 2025 in Kraft trat \u2014 gilt als ausgegeben, sobald Sie den Antrag einreichen. Priority und Super-Priority Zuzahlungen werden nur erstattet, wenn die Dienstleistung nie erbracht wurde.<\/p>\n<table>\n<thead>\n<tr>\n<th>Artikel<\/th>\n<th>Erstattbar nach Antragstellung?<\/th>\n<th>Anmerkungen<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Hauptvisumgeb\u00fchr<\/td>\n<td>Nein<\/td>\n<td>Geb\u00fchr f\u00fcr die Bearbeitung, nicht f\u00fcr die Genehmigung<\/td>\n<\/tr>\n<tr>\n<td>Immigration Health Surcharge<\/td>\n<td>Ja<\/td>\n<td>Automatisch erstattet bei R\u00fcckzug oder Ablehnung<\/td>\n<\/tr>\n<tr>\n<td>Priority \/ Super-Priority<\/td>\n<td>Manchmal<\/td>\n<td>Wird nur erstattet, wenn die Dienstleistung nicht in Anspruch genommen wurde<\/td>\n<\/tr>\n<tr>\n<td>Optionaler Kurierdienst \/ SMS<\/td>\n<td>Manchmal<\/td>\n<td>H\u00e4ngt vom Partner-Centre ab<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Stellen Sie sich vor: Sie haben im M\u00e4rz ein Besuchervisum bezahlt, dann wurde Ihre Gesch\u00e4ftsreise eine Woche sp\u00e4ter storniert. Sie ziehen sich vor der Biometrieerfassung zur\u00fcck. Die \u00a3127 bleiben bei UKVI, aber wenn Sie einen \u00a3500-Priorit\u00e4tsslot gekauft h\u00e4tten, den Sie nie wahrgenommen haben, sollte dieses Add-on zur\u00fcckgegeben werden. \u00dcberpr\u00fcfen Sie immer Ihr Partner-Centre-Dashboard, da die R\u00fcckgaberegeln zwischen TLScontact und VFS Global leicht unterschiedlich sind. Unser \u00dcberblick \u00fcber die <a href=\"https:\/\/visaeta.uk\/de\/blog\/cost-of-tourist-visa-for-uk\/\">Kosten f\u00fcr ein UK-Touristenvisum<\/a> zeigt genau, welche Zeilen optional sind.<\/p>\n<blockquote>\n<p><strong>Das ist wichtig:<\/strong> Ein R\u00fcckzug ist nicht dasselbe wie eine Ablehnung. Ein freiwilliger R\u00fcckzug hinterl\u00e4sst keine Ablehnung in Ihrer Akte, was f\u00fcr zuk\u00fcnftige Bewerbungen weitaus besser ist, als eine schwache Bewerbung ablehnen zu lassen. Falls Sie eine Ablehnung bef\u00fcrchten, ist ein R\u00fcckzug und die Behebung des Problems oft der intelligentere Schachzug.<\/p>\n<\/blockquote>\n<h2>Wie Sie sich nach einer Stornierung erneut bewerben<\/h2>\n<p><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"627\" src=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061994.jpg\" alt=\"Antragsteller, der sich darauf vorbereitet, ein UK-Visum mit neuen Dokumenten erneut zu beantragen\" class=\"wp-image-6795\" srcset=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061994.jpg 940w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061994-300x200.jpg 300w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061994-768x512.jpg 768w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061994-18x12.jpg 18w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/figure>\n<\/p>\n<p><strong>Sie k\u00f6nnen sich unmittelbar nach der Stornierung erneut bewerben \u2013 es gibt keine Wartezeit und keine Strafe, nur ein neues Formular und eine neue Geb\u00fchr.<\/strong> UK Visas and Immigration sperrt oder kennzeichnet Antragsteller nicht, die ihre Bewerbung zur\u00fcckziehen. Tats\u00e4chlich ist ein sauberer R\u00fcckzug gefolgt von einer st\u00e4rkeren Bewerbung ein anerkannter Weg, um Dokumente zu reparieren, die Sie beim ersten Mal nicht eingereicht haben.<\/p>\n<p>Starten Sie die neue Bewerbung \u00fcber <a href=\"https:\/\/www.gov.uk\/apply-to-come-to-the-uk\" target=\"_blank\" rel=\"noopener\">gov.uk Antragsdienst<\/a> (abgerufen am 1. Juli 2026) oder Ihr kommerzieller Partner. Verwenden Sie denselben Pass und erw\u00e4hnen Sie nichts \u00fcber die alte Anwendung, es sei denn, eine Frage fordert dies speziell an. Wenn Ihr erster Versuch aufgrund von Mitteln oder Absichten zu einer Ablehnung f\u00fchrte, nutzen Sie die L\u00fccke, um Ihre Beweise zu st\u00e4rken \u2013 ein klareres <a href=\"https:\/\/visaeta.uk\/de\/blog\/covering-letter-for-uk-visa-application\/\">Anschreiben<\/a> und vollst\u00e4ndige Kontoausz\u00fcge machen den Unterschied. Siehe unsere Liste von <a href=\"https:\/\/visaeta.uk\/de\/uncategorized\/documents-required-for-uk-visitor-visa-2026-costs-and-rules-explained\/\">f\u00fcr ein UK-Besuchervisum erforderliche Dokumente<\/a> bevor Sie erneut einreichen.<\/p>\n<p>Eine erneute Antragstellung hebt eine echte Ablehnung nicht auf. Wenn Ihr fr\u00fcherer Antrag tats\u00e4chlich abgelehnt und nicht zur\u00fcckgezogen wurde, lesen Sie <a href=\"https:\/\/visaeta.uk\/de\/blog\/how-to-appeal-a-uk-visa-rejection\/\">how to appeal a UK visa rejection<\/a> zun\u00e4chst, weil die Behebung unterschiedlich ist. Und wenn Sie einfach nur eine Anwendung verfolgen m\u00f6chten, die Sie behalten m\u00f6chten, lesen Sie unseren Leitfaden zu <a href=\"https:\/\/visaeta.uk\/de\/blog\/tracking-uk-visa-application\/\">Verfolgung einer UK-Visumantragstellung<\/a> deckt die Statusetappen ab.<\/p>\n<h2>Praktische Tipps vor Ihrer K\u00fcndigung<\/h2>\n<ul>\n<li><strong>Machen Sie von allem Screenshots:<\/strong> Die K\u00fcndigungsbest\u00e4tigung und jeder R\u00fcckerstattungsnachweis sch\u00fctzen Sie, falls eine Zahlung verloren geht.<\/li>\n<li><strong>\u00dcberpr\u00fcfen Sie zuerst den Visumtyp:<\/strong> Eine kurze Besucherroute und eine lange Arbeitsroute folgen unterschiedlichen R\u00fcckerstattungsregeln \u2014 <a href=\"https:\/\/www.gov.uk\/browse\/visas-immigration\" target=\"_blank\" rel=\"noopener\">gov.uk Visa- und Einwanderungshub<\/a> listet sie alle auf.<\/li>\n<li><strong>K\u00fcndigen Sie nicht wegen eines behebbaren Tippfehlers:<\/strong> Bitten Sie das Visazentrum, diese stattdessen zu \u00e4ndern.<\/li>\n<li><strong>Behalten Sie Ihre GWF-Nummer:<\/strong> Sie werden es f\u00fcr R\u00fcckerstattungen und f\u00fcr jede UKVI-Anfrage ben\u00f6tigen.<\/li>\n<li><strong>Falls Sie m\u00f6glicherweise stattdessen verl\u00e4ngern:<\/strong> ein Aufenthalt, den Sie verl\u00e4ngern m\u00f6chten, ist ein anderer Prozess \u2014 siehe <a href=\"https:\/\/visaeta.uk\/de\/blog\/how-can-i-extend-my-uk-visa\/\">wie man ein UK-Visum verl\u00e4ngert<\/a>.<\/li>\n<\/ul>\n<h2>H\u00e4ufig gestellte Fragen<\/h2>\n<h3>Kann ich UK ETA-Formulare stornieren und eine vollst\u00e4ndige R\u00fcckerstattung erhalten?<\/h3>\n<p>Nur wenn Sie vor dem Absenden und Bezahlen stornieren. Nach der Einreichung ist die Hauptvisumgeb\u00fchr nicht erstattbar, da sie die Bearbeitung abdeckt. Die Immigration Health Surcharge wird jedoch automatisch bei Ihrem R\u00fcckzug erstattet.<\/p>\n<h3>Wie kann ich einen UK ETA-Antrag nach der Biometrie zur\u00fcckziehen?<\/h3>\n<p>Sobald die Biometrie abgeschlossen ist und die Akte ein Entscheidungszentrum erreicht hat, funktioniert der Self-Service-R\u00fcckzug m\u00f6glicherweise nicht mehr. Kontaktieren Sie UKVI \u00fcber die offizielle Kontaktseite und geben Sie Ihre Referenznummer an. Sie k\u00f6nnen einen R\u00fcckzug vermerken, aber die Geb\u00fchr bleibt bestehen.<\/p>\n<h3>Schadet mir eine Stornierung bei zuk\u00fcnftigen UK-Antr\u00e4gen?<\/h3>\n<p>Nein. Ein freiwilliger R\u00fcckzug ist keine Ablehnung und hinterl\u00e4sst keine negativen Spuren. Es ist oft besser, eine schwache Anwendung zur\u00fcckzuziehen, als eine formelle Ablehnung zu erhalten, die Sie sp\u00e4ter in Formularen angeben m\u00fcssen.<\/p>\n<h3>Wie lange dauert eine R\u00fcckerstattung der Immigration Health Surcharge?<\/h3>\n<p>Es wird automatisch auf Ihre urspr\u00fcngliche Zahlungskarte \u00fcberwiesen, normalerweise innerhalb weniger Wochen nach Best\u00e4tigung der Abhebung. Wenn es nach sechs Wochen nicht angekommen ist, kontaktieren Sie UKVI mit Ihrer Zahlungsreferenz.<\/p>\n<h3>Kann ich mich sofort nach dem R\u00fcckzug neu bewerben?<\/h3>\n<p>Ja. Es gibt keine Bedenkzeit. Sie reichen einen neuen Antrag ein und zahlen eine neue Geb\u00fchr. Nutzen Sie die Pause, um das Schwache zu beheben \u2013 Fondsnachweise, Termine oder Ihr Anschreiben.<\/p>\n<h3>Ist ein R\u00fcckzug dasselbe wie eine Beschwerde?<\/h3>\n<p>Nein. Ein R\u00fcckzug stoppt eine Bewerbung, die Sie eingeleitet haben; eine Beschwerde wendet sich gegen eine Ablehnung, die Sie bereits erhalten haben. Wenn Ihre Bewerbung abgelehnt wurde, ist eine Beschwerde oder Verwaltungs\u00fcberpr\u00fcfung der richtige Weg, nicht ein neuer R\u00fcckzug.<\/p>\n<h3>Was ist, wenn die Schaltfl\u00e4che \u201eZur\u00fcckziehen\" nicht angezeigt wird?<\/h3>\n<p>Einige Partner-Center-Dashboards blenden die Option aus, sobald die Bearbeitung beginnt. Senden Sie in diesem Fall eine E-Mail direkt an UK Visas and Immigration, teilen Sie mit, dass Sie sich zur\u00fcckziehen m\u00f6chten, und geben Sie Ihre GWF-Nummer und Passdaten an.<\/p>\n<p><em>Zuletzt aktualisiert: 2026-07-01 \u2014 \u00fcberpr\u00fcft gegen gov.uk-Zeitplan.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>You can cancel a visa application UK applicants have started at almost any point before a decision is made, but what you get back depends on timing. Withdraw before you pay and nothing is lost. Withdraw after you submit and pay, and the visa fee is gone \u2014 though an unused biometric slot or courier [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6796,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[132],"tags":[194],"class_list":["post-6797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uk-eta-vs-visa","tag-source-kgr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cancel Visa Application UK: 2026 Withdraw &amp; Refund Guide<\/title>\n<meta name=\"description\" content=\"How to cancel a visa application UK travellers submitted: withdraw steps, which fees are refundable, and how to reapply cleanly in 2026.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visaeta.uk\/de\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cancel Visa Application UK: 2026 Withdraw &amp; Refund Guide\" \/>\n<meta property=\"og:description\" content=\"How to cancel a visa application UK travellers submitted: withdraw steps, which fees are refundable, and how to reapply cleanly in 2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visaeta.uk\/de\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"ETA VISA UK\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T08:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061992.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VisaETA Editorial Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"VisaETA Editorial Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/\"},\"author\":{\"name\":\"VisaETA Editorial Team\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#\\\/schema\\\/person\\\/81b5965766d02d43333b31730f5fa1c3\"},\"headline\":\"How to Cancel or Withdraw a UK Visa Application (2026)\",\"datePublished\":\"2026-09-02T08:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/\"},\"wordCount\":1518,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visaeta.uk\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/visaeta-8061992.jpg\",\"keywords\":[\"source-kgr\"],\"articleSection\":[\"UK ETA vs Visa\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/\",\"url\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/\",\"name\":\"Cancel Visa Application UK: 2026 Withdraw & Refund Guide\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visaeta.uk\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/visaeta-8061992.jpg\",\"datePublished\":\"2026-09-02T08:00:00+00:00\",\"description\":\"How to cancel a visa application UK travellers submitted: withdraw steps, which fees are refundable, and how to reapply cleanly in 2026.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visaeta.uk\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/visaeta-8061992.jpg\",\"contentUrl\":\"https:\\\/\\\/visaeta.uk\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/visaeta-8061992.jpg\",\"width\":940,\"height\":627,\"caption\":\"Cancel visa application UK concept with passport, laptop and paperwork\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/visaeta.uk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to Cancel or Withdraw a UK Visa Application (2026)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#website\",\"url\":\"https:\\\/\\\/visaeta.uk\\\/\",\"name\":\"ETA VISA TO THE GREAT BRITAIN - UK\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#organization\"},\"alternateName\":\"ETA visa to the UK\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visaeta.uk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#organization\",\"name\":\"ETA VISA UK\",\"url\":\"https:\\\/\\\/visaeta.uk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visaeta.uk\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-ETA-UK-2.png\",\"contentUrl\":\"https:\\\/\\\/visaeta.uk\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-ETA-UK-2.png\",\"width\":269,\"height\":53,\"caption\":\"ETA VISA UK\"},\"image\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#\\\/schema\\\/person\\\/81b5965766d02d43333b31730f5fa1c3\",\"name\":\"VisaETA Editorial Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77324b0d1ba9a1c5a0b04ea41b2c3f26d5e8eefd0ee6b4f256de4805c6ebd71c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77324b0d1ba9a1c5a0b04ea41b2c3f26d5e8eefd0ee6b4f256de4805c6ebd71c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77324b0d1ba9a1c5a0b04ea41b2c3f26d5e8eefd0ee6b4f256de4805c6ebd71c?s=96&d=mm&r=g\",\"caption\":\"VisaETA Editorial Team\"},\"sameAs\":[\"http:\\\/\\\/visaeta.uk\"],\"url\":\"https:\\\/\\\/visaeta.uk\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UK ETA stornieren: 2026 R\u00fcckzugs- und R\u00fcckerstattungsleitfaden","description":"So stornieren Sie einen UK ETA-Antrag, den Reisende eingereicht haben: R\u00fcckzugsschritte, welche Geb\u00fchren erstattbar sind und wie Sie 2026 sauber erneut beantragen k\u00f6nnen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visaeta.uk\/de\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/","og_locale":"de_DE","og_type":"article","og_title":"Cancel Visa Application UK: 2026 Withdraw & Refund Guide","og_description":"How to cancel a visa application UK travellers submitted: withdraw steps, which fees are refundable, and how to reapply cleanly in 2026.","og_url":"https:\/\/visaeta.uk\/de\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/","og_site_name":"ETA VISA UK","article_published_time":"2026-09-02T08:00:00+00:00","og_image":[{"width":940,"height":627,"url":"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061992.jpg","type":"image\/jpeg"}],"author":"VisaETA Editorial Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"VisaETA Editorial Team","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#article","isPartOf":{"@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/"},"author":{"name":"VisaETA Editorial Team","@id":"https:\/\/visaeta.uk\/#\/schema\/person\/81b5965766d02d43333b31730f5fa1c3"},"headline":"How to Cancel or Withdraw a UK Visa Application (2026)","datePublished":"2026-09-02T08:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/"},"wordCount":1518,"commentCount":0,"publisher":{"@id":"https:\/\/visaeta.uk\/#organization"},"image":{"@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061992.jpg","keywords":["source-kgr"],"articleSection":["UK ETA vs Visa"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/","url":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/","name":"UK ETA stornieren: 2026 R\u00fcckzugs- und R\u00fcckerstattungsleitfaden","isPartOf":{"@id":"https:\/\/visaeta.uk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#primaryimage"},"image":{"@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061992.jpg","datePublished":"2026-09-02T08:00:00+00:00","description":"So stornieren Sie einen UK ETA-Antrag, den Reisende eingereicht haben: R\u00fcckzugsschritte, welche Geb\u00fchren erstattbar sind und wie Sie 2026 sauber erneut beantragen k\u00f6nnen.","breadcrumb":{"@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#primaryimage","url":"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061992.jpg","contentUrl":"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061992.jpg","width":940,"height":627,"caption":"Cancel visa application UK concept with passport, laptop and paperwork"},{"@type":"BreadcrumbList","@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/visaeta.uk\/"},{"@type":"ListItem","position":2,"name":"How to Cancel or Withdraw a UK Visa Application (2026)"}]},{"@type":"WebSite","@id":"https:\/\/visaeta.uk\/#website","url":"https:\/\/visaeta.uk\/","name":"ETA-VISUM F\u00dcR DAS VEREINIGTE K\u00d6NIGREICH - UK","description":"","publisher":{"@id":"https:\/\/visaeta.uk\/#organization"},"alternateName":"ETA visa to the UK","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visaeta.uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/visaeta.uk\/#organization","name":"ETA-Visum UK","url":"https:\/\/visaeta.uk\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visaeta.uk\/#\/schema\/logo\/image\/","url":"https:\/\/visaeta.uk\/wp-content\/uploads\/2023\/11\/cropped-ETA-UK-2.png","contentUrl":"https:\/\/visaeta.uk\/wp-content\/uploads\/2023\/11\/cropped-ETA-UK-2.png","width":269,"height":53,"caption":"ETA VISA UK"},"image":{"@id":"https:\/\/visaeta.uk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/visaeta.uk\/#\/schema\/person\/81b5965766d02d43333b31730f5fa1c3","name":"VisaETA Redaktionsteam","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/77324b0d1ba9a1c5a0b04ea41b2c3f26d5e8eefd0ee6b4f256de4805c6ebd71c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/77324b0d1ba9a1c5a0b04ea41b2c3f26d5e8eefd0ee6b4f256de4805c6ebd71c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/77324b0d1ba9a1c5a0b04ea41b2c3f26d5e8eefd0ee6b4f256de4805c6ebd71c?s=96&d=mm&r=g","caption":"VisaETA Editorial Team"},"sameAs":["http:\/\/visaeta.uk"],"url":"https:\/\/visaeta.uk\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/visaeta.uk\/de\/wp-json\/wp\/v2\/posts\/6797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaeta.uk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaeta.uk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaeta.uk\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visaeta.uk\/de\/wp-json\/wp\/v2\/comments?post=6797"}],"version-history":[{"count":1,"href":"https:\/\/visaeta.uk\/de\/wp-json\/wp\/v2\/posts\/6797\/revisions"}],"predecessor-version":[{"id":6966,"href":"https:\/\/visaeta.uk\/de\/wp-json\/wp\/v2\/posts\/6797\/revisions\/6966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaeta.uk\/de\/wp-json\/wp\/v2\/media\/6796"}],"wp:attachment":[{"href":"https:\/\/visaeta.uk\/de\/wp-json\/wp\/v2\/media?parent=6797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaeta.uk\/de\/wp-json\/wp\/v2\/categories?post=6797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaeta.uk\/de\/wp-json\/wp\/v2\/tags?post=6797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}