{"id":6797,"date":"2026-09-02T09:00:00","date_gmt":"2026-09-02T08:00:00","guid":{"rendered":"https:\/\/visaeta.uk\/?p=6797"},"modified":"2026-08-28T05:00:10","modified_gmt":"2026-08-28T04:00:10","slug":"cancel-visa-application-uk-2026","status":"publish","type":"post","link":"https:\/\/visaeta.uk\/fr\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/","title":{"rendered":"Comment annuler ou retirer une demande de visa UK (2026)"},"content":{"rendered":"<p><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"627\" src=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061949.jpg\" alt=\"Personne annulant une demande de visa UK sur un ordinateur portable avec passeport \u00e0 proximit\u00e9\" class=\"wp-image-6791\" srcset=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061949.jpg 940w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061949-300x200.jpg 300w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061949-768x512.jpg 768w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061949-18x12.jpg 18w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/figure>\n<\/p>\n<p><strong>Vous pouvez annuler une demande de visa UK que les demandeurs ont commenc\u00e9e \u00e0 presque n'importe quel moment avant qu'une d\u00e9cision soit prise, mais ce que vous r\u00e9cup\u00e9rez d\u00e9pend du moment.<\/strong> Retirez avant de payer et vous ne perdrez rien. Retirez apr\u00e8s avoir soumis et pay\u00e9, et les frais de visa disparaissent \u2014 bien qu'un cr\u00e9neau biom\u00e9trique inutilis\u00e9 ou un service de coursier suppl\u00e9mentaire puisse parfois \u00eatre rembours\u00e9. Ce guide explique les \u00e9tapes exactes, l'aspect financier et comment refaire une demande correctement.<\/p>\n<p><strong>R\u00e9sum\u00e9 :<\/strong> Pour annuler une demande de visa, les voyageurs britanniques doivent la retirer par leur compte UKVI ou aupr\u00e8s d'un partenaire commercial (TLScontact ou VFS Global) avant la biom\u00e9trie. Les frais de visa principaux ne sont pas remboursables une fois soumis, mais la taxe sanitaire pour l'immigration et certains services optionnels sont rembours\u00e9s automatiquement. Une nouvelle demande est autoris\u00e9e imm\u00e9diatement avec un nouveau formulaire et paiement.<\/p>\n<table>\n<thead>\n<tr>\n<th>Faits cl\u00e9s<\/th>\n<th>D\u00e9tail<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>O\u00f9 annuler<\/td>\n<td>Compte UKVI \/ TLScontact \/ VFS Global<\/td>\n<\/tr>\n<tr>\n<td>Frais de visa remboursables ?<\/td>\n<td>Non, une fois la demande soumise<\/td>\n<\/tr>\n<tr>\n<td>IHS remboursable ?<\/td>\n<td>Oui \u2014 rembours\u00e9 automatiquement si le visa est retir\u00e9 ou refus\u00e9<\/td>\n<\/tr>\n<tr>\n<td>Refaire une demande apr\u00e8s annulation ?<\/td>\n<td>Oui, imm\u00e9diatement, avec une nouvelle demande et des frais<\/td>\n<\/tr>\n<tr>\n<td>Temps de d\u00e9cision standard<\/td>\n<td>Environ 3 semaines pour un visa Standard Visitor<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Les plans changent. Peut-\u00eatre que votre voyage a \u00e9chou\u00e9, peut-\u00eatre que vous avez rep\u00e9r\u00e9 une erreur sur le formulaire, ou peut-\u00eatre que vous avez simplement choisi la mauvaise route de visa. Quelle que soit la raison, vous n'\u00eates pas coinc\u00e9 avec une demande que vous ne voulez plus. Voici ce qui se passe r\u00e9ellement quand vous arr\u00eatez, et comment prot\u00e9ger votre argent. Si vous pesez toujours la route elle-m\u00eame, notre <a href=\"https:\/\/visaeta.uk\/fr\/blog\/applying-for-a-standard-visitor-visa-to-the-uk-a-step-by-step-guide\/\">guide \u00e9tape par \u00e9tape du visa Standard Visitor<\/a> est un bon point de d\u00e9part.<\/p>\n<h2>Pouvez-vous annuler les formulaires de demande de visa UK apr\u00e8s les avoir soumis ?<\/h2>\n<p><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"627\" src=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-33497885.jpg\" alt=\"Formulaire de demande de visa UK et passeport sur un bureau en bois\" class=\"wp-image-6792\" srcset=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-33497885.jpg 940w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-33497885-300x200.jpg 300w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-33497885-768x512.jpg 768w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-33497885-18x12.jpg 18w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/figure>\n<\/p>\n<p><strong>Oui \u2014 vous pouvez annuler les formulaires de demande de visa UK apr\u00e8s les avoir soumis, mais les frais de visa principal ne seront pas rembours\u00e9s.<\/strong> UK Visas and Immigration consid\u00e8re les frais comme un paiement pour le traitement, et le traitement commence d\u00e8s que vous soumettez votre demande. Retrait avant paiement et vous ne devez rien. Retrait apr\u00e8s paiement mais avant la biom\u00e9trie, et vous perdez les frais de visa tout en conservant les suppl\u00e9ments remboursables. Le <a href=\"https:\/\/www.gov.uk\/visa-fees\" target=\"_blank\" rel=\"noopener\">page officielle des frais de visa UK<\/a> (gov.uk, consult\u00e9 le 1er juillet 2026) confirme que les frais sont factur\u00e9s par demande, et non par r\u00e9sultat.<\/p>\n<p>Il y a un c\u00f4t\u00e9 positif. La redevance pour la sant\u00e9 dans le cadre de l'immigration \u2014 souvent la plus grosse ligne unique sur une demande de long s\u00e9jour \u2014 est rembours\u00e9e automatiquement lorsqu'une demande est retir\u00e9e ou refus\u00e9e. La <a href=\"https:\/\/www.gov.uk\/apply-to-come-to-the-uk\" target=\"_blank\" rel=\"noopener\">portail de demande UKVI<\/a> processus qui remboursent sur votre carte d'origine, g\u00e9n\u00e9ralement dans quelques semaines. Les visas de visiteur de courte dur\u00e9e n'incluent pas la surtaxe, donc cela aide principalement les demandeurs de travail et d'\u00e9tudes.<\/p>\n<blockquote>\n<p><strong>Conseil pratique :<\/strong> N'annulez pas simplement parce que vous avez remarqu\u00e9 une petite erreur. De nombreuses erreurs \u2014 une faute de frappe dans une adresse, un mauvais num\u00e9ro de t\u00e9l\u00e9phone \u2014 peuvent \u00eatre corrig\u00e9es \u00e0 votre rendez-vous biom\u00e9trique ou en contactant le centre de visas. L'annulation et le red\u00e9marrage vous co\u00fbtent l'int\u00e9gralit\u00e9 des frais \u00e0 nouveau.<\/p>\n<\/blockquote>\n<h2>Comment retirer une demande de visa UK \u00e9tape par \u00e9tape<\/h2>\n<p><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"627\" src=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061944.jpg\" alt=\"Voyageur examinant les \u00e9tapes de retrait d&#039;une demande de visa UK sur un t\u00e9l\u00e9phone\" class=\"wp-image-6793\" srcset=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061944.jpg 940w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061944-300x200.jpg 300w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061944-768x512.jpg 768w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061944-18x12.jpg 18w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/figure>\n<\/p>\n<p><strong>Pour vous retirer, connectez-vous au compte que vous avez utilis\u00e9 pour postuler, ouvrez la demande en attente et choisissez l'option de retrait \u2014 la plupart des annulations prennent moins de dix minutes.<\/strong> Le bouton exact d\u00e9pend de l'endroit o\u00f9 vous avez pr\u00e9sent\u00e9 votre demande. Les demandeurs en dehors du Royaume-Uni utilisent g\u00e9n\u00e9ralement TLScontact ou VFS Global ; les demandeurs au Royaume-Uni utilisent le service en ligne UKVI. Si vous ne trouvez pas l'option, contactez directement UK Visas and Immigration.<\/p>\n<ol>\n<li><strong>Se connecter<\/strong> vers votre compte UKVI, TLScontact ou VFS Global avec l'e-mail que vous avez enregistr\u00e9.<\/li>\n<li><strong>Ouvrez la demande active<\/strong> et v\u00e9rifiez son statut. S'il indique d\u00e9j\u00e0 &#8220;en cours&#8221; dans un centre de prise de d\u00e9cision, un retrait ne pourra peut-\u00eatre plus l'arr\u00eater.<\/li>\n<li><strong>S\u00e9lectionnez &#8220;retirer&#8221; ou &#8220;annuler&#8221;<\/strong> et confirmez. Prenez une capture d'\u00e9cran de l'\u00e9cran de confirmation.<\/li>\n<li><strong>Annulez votre rendez-vous biom\u00e9trique<\/strong> s\u00e9par\u00e9ment si le syst\u00e8me ne le fait pas pour vous.<\/li>\n<li><strong>Attendez l'e-mail de confirmation.<\/strong> Conservez-le \u2014 vous pourriez avoir besoin d'une preuve de retrait si vous soumettiez une nouvelle demande.<\/li>\n<\/ol>\n<p>Si aucune option libre-service n'appara\u00eet, utilisez le <a href=\"https:\/\/www.gov.uk\/contact-ukvi-inside-outside-uk\" target=\"_blank\" rel=\"noopener\">page de contact officielle de l'UKVI<\/a> (gov.uk, consult\u00e9 le 1er juillet 2026) pour demander un retrait par courriel ou t\u00e9l\u00e9phone. Indiquez votre num\u00e9ro GWF ou de r\u00e9f\u00e9rence de demande sur la premi\u00e8re ligne \u2014 cela acc\u00e9l\u00e8re les choses. Pour les d\u00e9lais de traitement qui affectent la possibilit\u00e9 d'un retrait, consultez notre guide sur <a href=\"https:\/\/visaeta.uk\/fr\/blog\/how-long-does-uk-visa-processing-take-a-detailed-guide\/\">combien de temps prend le traitement des demandes de visa UK<\/a>.<\/p>\n<h2>Ce qu'il advient de votre argent et de vos frais<\/h2>\n<p><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"627\" src=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061986.jpg\" alt=\"Carte bancaire et documents montrant l&#039;examen des frais de visa UK\" class=\"wp-image-6794\" srcset=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061986.jpg 940w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061986-300x200.jpg 300w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061986-768x512.jpg 768w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061986-18x12.jpg 18w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/figure>\n<\/p>\n<p><strong>Une fois soumis, les frais de visa ne sont pas remboursables, mais la contribution de sant\u00e9 et certains services optionnels sont retourn\u00e9s.<\/strong> C'est la partie qui d\u00e9route les gens. Une taxe de visa de visiteur standard de six mois \u2014 indiqu\u00e9e \u00e0 \u00a3127 sur le tableau des frais en vigueur apr\u00e8s l'augmentation du 9 avril 2025 \u2014 est consid\u00e9r\u00e9e comme d\u00e9pens\u00e9e d\u00e8s que vous la d\u00e9posez. Les suppl\u00e9ments prioritaires et super-prioritaires ne sont remboursables que si le service n'a jamais \u00e9t\u00e9 fourni.<\/p>\n<table>\n<thead>\n<tr>\n<th>Article<\/th>\n<th>Remboursable apr\u00e8s soumission ?<\/th>\n<th>Notes<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Frais de visa principaux<\/td>\n<td>Non<\/td>\n<td>Factur\u00e9 pour le traitement, non pour l'approbation<\/td>\n<\/tr>\n<tr>\n<td>Contribution de sant\u00e9 pour l'immigration<\/td>\n<td>Oui<\/td>\n<td>Rembours\u00e9 automatiquement en cas de retrait ou de refus<\/td>\n<\/tr>\n<tr>\n<td>Prioritaire \/ super-prioritaire<\/td>\n<td>Parfois<\/td>\n<td>Rembours\u00e9 uniquement si le service n'a pas \u00e9t\u00e9 utilis\u00e9<\/td>\n<\/tr>\n<tr>\n<td>Coursier \/ SMS facultatif<\/td>\n<td>Parfois<\/td>\n<td>D\u00e9pend du centre partenaire<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Imaginez ceci. Vous avez pay\u00e9 un visa de visiteur en mars, puis votre voyage professionnel a \u00e9t\u00e9 annul\u00e9 une semaine plus tard. Vous vous retirez avant la biom\u00e9trie. Les 127 \u00a3 restent avec l'UKVI, mais si vous aviez achet\u00e9 un cr\u00e9neau prioritaire de 500 \u00a3 auquel vous n'avez pas assist\u00e9, ce service suppl\u00e9mentaire devrait \u00eatre rembours\u00e9. V\u00e9rifiez toujours le tableau de bord de votre centre partenaire, car les r\u00e8gles de remboursement diff\u00e8rent l\u00e9g\u00e8rement entre TLScontact et VFS Global. Notre analyse du <a href=\"https:\/\/visaeta.uk\/fr\/blog\/cost-of-tourist-visa-for-uk\/\">co\u00fbt d'un visa touristique britannique<\/a> montre exactement quelles lignes sont facultatives.<\/p>\n<blockquote>\n<p><strong>Important :<\/strong> Un retrait n'est pas la m\u00eame chose qu'un refus. Un retrait volontaire ne laisse pas de refus dans vos ant\u00e9c\u00e9dents, ce qui est bien mieux pour les demandes futures que de laisser rejeter une demande faible. Si vous craignez un refus, retirer et corriger le probl\u00e8me est souvent le choix plus intelligent.<\/p>\n<\/blockquote>\n<h2>Comment r\u00e9demander apr\u00e8s votre annulation<\/h2>\n<p><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"627\" src=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061994.jpg\" alt=\"Demandeur se pr\u00e9parant \u00e0 pr\u00e9senter \u00e0 nouveau une demande de visa UK avec des documents actualis\u00e9s\" class=\"wp-image-6795\" srcset=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061994.jpg 940w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061994-300x200.jpg 300w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061994-768x512.jpg 768w, https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061994-18x12.jpg 18w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/figure>\n<\/p>\n<p><strong>Vous pouvez r\u00e9demander imm\u00e9diatement apr\u00e8s l'annulation \u2014 il n'y a pas de p\u00e9riode d'attente et pas de p\u00e9nalit\u00e9, juste un formulaire neuf et des frais nouveaux.<\/strong> UK Visas and Immigration ne refuse pas et ne &#8220;signale&#8221; pas les demandeurs qui se retirent. En fait, un retrait en bonne et due forme suivi d'une demande plus solide est un moyen reconnu de corriger les documents que vous aviez oubli\u00e9s la premi\u00e8re fois.<\/p>\n<p>Commencez la nouvelle demande via le <a href=\"https:\/\/www.gov.uk\/apply-to-come-to-the-uk\" target=\"_blank\" rel=\"noopener\">service de demande gov.uk<\/a> (consult\u00e9 le 1er juillet 2026) ou votre partenaire commercial. Utilisez le m\u00eame passeport et ne mentionnez rien sur l'ancienne demande \u00e0 moins qu'une question ne vous le demande sp\u00e9cifiquement. Si votre premi\u00e8re tentative s'orientait vers un refus en raison des fonds ou de l'intention, utilisez l'intervalle pour renforcer vos preuves \u2014 une <a href=\"https:\/\/visaeta.uk\/fr\/blog\/covering-letter-for-uk-visa-application\/\">lettre de motivation<\/a> et les relev\u00e9s bancaires complets font la diff\u00e9rence. Voir notre liste de <a href=\"https:\/\/visaeta.uk\/fr\/uncategorized\/documents-required-for-uk-visitor-visa-2026-costs-and-rules-explained\/\">documents requis pour un visa de visiteur au Royaume-Uni<\/a> avant de pr\u00e9senter une nouvelle demande.<\/p>\n<p>La nouvelle demande n'annule pas un refus v\u00e9ritable, cependant. Si votre demande ant\u00e9rieure a \u00e9t\u00e9 r\u00e9ellement refus\u00e9e plut\u00f4t que retir\u00e9e, lisez <a href=\"https:\/\/visaeta.uk\/fr\/blog\/how-to-appeal-a-uk-visa-rejection\/\">comment contester un refus de visa UK<\/a> d'abord, car la correction est diff\u00e9rente. Et si vous voulez simplement suivre une demande que vous avez d\u00e9cid\u00e9 de conserver, notre guide sur <a href=\"https:\/\/visaeta.uk\/fr\/blog\/tracking-uk-visa-application\/\">suivi d'une demande de visa UK<\/a> couvre les \u00e9tapes de statut.<\/p>\n<h2>Conseils pratiques avant d'annuler<\/h2>\n<ul>\n<li><strong>Capturez tout en capture d'\u00e9cran :<\/strong> la confirmation de retrait et toute r\u00e9f\u00e9rence de remboursement vous prot\u00e8gent si un paiement est perdu.<\/li>\n<li><strong>V\u00e9rifiez d'abord le type de visa :<\/strong> une courte route de visiteur et une longue route de travail suivent des r\u00e8gles de remboursement diff\u00e9rentes \u2014 <a href=\"https:\/\/www.gov.uk\/browse\/visas-immigration\" target=\"_blank\" rel=\"noopener\">gov.uk hub des visas et de l'immigration<\/a> les \u00e9num\u00e8re tous.<\/li>\n<li><strong>Ne pas annuler pour une simple faute de frappe :<\/strong> demandez au centre de visas de le modifier \u00e0 la place.<\/li>\n<li><strong>Conservez votre num\u00e9ro GWF :<\/strong> vous en aurez besoin pour les remboursements et pour toute demande de renseignements de l'UKVI.<\/li>\n<li><strong>Si vous envisagez plut\u00f4t une prolongation :<\/strong> un s\u00e9jour que vous souhaitez prolonger est un processus diff\u00e9rent \u2014 voir <a href=\"https:\/\/visaeta.uk\/fr\/blog\/how-can-i-extend-my-uk-visa\/\">comment prolonger un visa UK<\/a>.<\/li>\n<\/ul>\n<h2>Questions fr\u00e9quemment pos\u00e9es<\/h2>\n<h3>Puis-je annuler un formulaire de demande de visa UK et obtenir un remboursement complet ?<\/h3>\n<p>Uniquement si vous annulez avant de soumettre et payer. Apr\u00e8s la soumission, les frais principaux de visa ne sont pas remboursables, car ils couvrent le traitement. La Surcharge d'Immigration, cependant, est rembours\u00e9e automatiquement lorsque vous vous retirez.<\/p>\n<h3>Comment retirer une demande de visa UK apr\u00e8s les donn\u00e9es biom\u00e9triques ?<\/h3>\n<p>Une fois les donn\u00e9es biom\u00e9triques collect\u00e9es et le dossier arriv\u00e9 \u00e0 un centre de d\u00e9cision, le retrait en libre-service peut ne plus fonctionner. Contactez l'UKVI via la page de contact officielle et citez votre num\u00e9ro de r\u00e9f\u00e9rence. Ils peuvent enregistrer un retrait, mais les frais restent dus.<\/p>\n<h3>L'annulation nuira-t-elle \u00e0 mes futures demandes de visa UK ?<\/h3>\n<p>Non. Un retrait volontaire n'est pas un refus et ne laisse aucune trace n\u00e9gative. Il est souvent pr\u00e9f\u00e9rable de retirer une demande faible que de recevoir un refus formel, que vous devrez d\u00e9clarer sur les formulaires ult\u00e9rieurs.<\/p>\n<h3>Combien de temps faut-il pour un remboursement de la Surcharge d'Immigration ?<\/h3>\n<p>Elle est \u00e9mise automatiquement sur votre carte de paiement d'origine, g\u00e9n\u00e9ralement dans quelques semaines suivant la confirmation du retrait. Si elle n'est pas arriv\u00e9e apr\u00e8s six semaines, contactez UKVI avec votre r\u00e9f\u00e9rence de paiement.<\/p>\n<h3>Puis-je pr\u00e9senter une nouvelle demande imm\u00e9diatement apr\u00e8s mon retrait ?<\/h3>\n<p>Oui. Il n'y a pas de d\u00e9lai de r\u00e9tractation. Vous soumettez une nouvelle demande et payez une nouvelle cotisation. Utilisez cette pause pour corriger ce qui \u00e9tait faible \u2014 preuves de fonds, dates, ou votre lettre de soutien.<\/p>\n<h3>Se retirer est-il la m\u00eame chose qu'un appel ?<\/h3>\n<p>Non. Se retirer arr\u00eate une demande que vous avez commenc\u00e9e ; un appel conteste un refus que vous avez d\u00e9j\u00e0 re\u00e7u. Si votre demande a \u00e9t\u00e9 refus\u00e9e, un appel ou un examen administratif est la bonne d\u00e9marche, pas un nouveau retrait.<\/p>\n<h3>Que faire si le bouton de retrait n'appara\u00eet pas ?<\/h3>\n<p>Certains tableaux de bord des centres partenaires masquent l'option une fois le traitement commenc\u00e9. Dans ce cas, contactez directement UK Visas and Immigration, indiquez que vous souhaitez vous retirer, et incluez votre num\u00e9ro GWF et les d\u00e9tails de votre passeport.<\/p>\n<p><em>Last updated: 2026-07-01 \u2014 verified against gov.uk schedule.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>You can cancel a visa application UK applicants have started at almost any point before a decision is made, but what you get back depends on timing. Withdraw before you pay and nothing is lost. Withdraw after you submit and pay, and the visa fee is gone \u2014 though an unused biometric slot or courier [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6796,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[132],"tags":[194],"class_list":["post-6797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uk-eta-vs-visa","tag-source-kgr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cancel Visa Application UK: 2026 Withdraw &amp; Refund Guide<\/title>\n<meta name=\"description\" content=\"How to cancel a visa application UK travellers submitted: withdraw steps, which fees are refundable, and how to reapply cleanly in 2026.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visaeta.uk\/fr\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cancel Visa Application UK: 2026 Withdraw &amp; Refund Guide\" \/>\n<meta property=\"og:description\" content=\"How to cancel a visa application UK travellers submitted: withdraw steps, which fees are refundable, and how to reapply cleanly in 2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visaeta.uk\/fr\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"ETA VISA UK\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T08:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061992.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VisaETA Editorial Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"VisaETA Editorial Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/\"},\"author\":{\"name\":\"VisaETA Editorial Team\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#\\\/schema\\\/person\\\/81b5965766d02d43333b31730f5fa1c3\"},\"headline\":\"How to Cancel or Withdraw a UK Visa Application (2026)\",\"datePublished\":\"2026-09-02T08:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/\"},\"wordCount\":1518,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visaeta.uk\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/visaeta-8061992.jpg\",\"keywords\":[\"source-kgr\"],\"articleSection\":[\"UK ETA vs Visa\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/\",\"url\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/\",\"name\":\"Cancel Visa Application UK: 2026 Withdraw & Refund Guide\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visaeta.uk\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/visaeta-8061992.jpg\",\"datePublished\":\"2026-09-02T08:00:00+00:00\",\"description\":\"How to cancel a visa application UK travellers submitted: withdraw steps, which fees are refundable, and how to reapply cleanly in 2026.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visaeta.uk\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/visaeta-8061992.jpg\",\"contentUrl\":\"https:\\\/\\\/visaeta.uk\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/visaeta-8061992.jpg\",\"width\":940,\"height\":627,\"caption\":\"Cancel visa application UK concept with passport, laptop and paperwork\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/blog\\\/uk-eta-vs-visa\\\/cancel-visa-application-uk-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/visaeta.uk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to Cancel or Withdraw a UK Visa Application (2026)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#website\",\"url\":\"https:\\\/\\\/visaeta.uk\\\/\",\"name\":\"ETA VISA TO THE GREAT BRITAIN - UK\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#organization\"},\"alternateName\":\"ETA visa to the UK\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visaeta.uk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#organization\",\"name\":\"ETA VISA UK\",\"url\":\"https:\\\/\\\/visaeta.uk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visaeta.uk\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-ETA-UK-2.png\",\"contentUrl\":\"https:\\\/\\\/visaeta.uk\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-ETA-UK-2.png\",\"width\":269,\"height\":53,\"caption\":\"ETA VISA UK\"},\"image\":{\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/visaeta.uk\\\/#\\\/schema\\\/person\\\/81b5965766d02d43333b31730f5fa1c3\",\"name\":\"VisaETA Editorial Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77324b0d1ba9a1c5a0b04ea41b2c3f26d5e8eefd0ee6b4f256de4805c6ebd71c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77324b0d1ba9a1c5a0b04ea41b2c3f26d5e8eefd0ee6b4f256de4805c6ebd71c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77324b0d1ba9a1c5a0b04ea41b2c3f26d5e8eefd0ee6b4f256de4805c6ebd71c?s=96&d=mm&r=g\",\"caption\":\"VisaETA Editorial Team\"},\"sameAs\":[\"http:\\\/\\\/visaeta.uk\"],\"url\":\"https:\\\/\\\/visaeta.uk\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Annuler une demande de visa UK : Guide 2026 de retrait et remboursement","description":"Comment annuler une demande de visa UK que les voyageurs ont soumise : \u00e9tapes de retrait, quels frais sont remboursables, et comment faire une nouvelle demande propre en 2026.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visaeta.uk\/fr\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Cancel Visa Application UK: 2026 Withdraw & Refund Guide","og_description":"How to cancel a visa application UK travellers submitted: withdraw steps, which fees are refundable, and how to reapply cleanly in 2026.","og_url":"https:\/\/visaeta.uk\/fr\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/","og_site_name":"ETA VISA UK","article_published_time":"2026-09-02T08:00:00+00:00","og_image":[{"width":940,"height":627,"url":"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061992.jpg","type":"image\/jpeg"}],"author":"VisaETA Editorial Team","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"VisaETA Editorial Team","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#article","isPartOf":{"@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/"},"author":{"name":"VisaETA Editorial Team","@id":"https:\/\/visaeta.uk\/#\/schema\/person\/81b5965766d02d43333b31730f5fa1c3"},"headline":"How to Cancel or Withdraw a UK Visa Application (2026)","datePublished":"2026-09-02T08:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/"},"wordCount":1518,"commentCount":0,"publisher":{"@id":"https:\/\/visaeta.uk\/#organization"},"image":{"@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061992.jpg","keywords":["source-kgr"],"articleSection":["UK ETA vs Visa"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/","url":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/","name":"Annuler une demande de visa UK : Guide 2026 de retrait et remboursement","isPartOf":{"@id":"https:\/\/visaeta.uk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#primaryimage"},"image":{"@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061992.jpg","datePublished":"2026-09-02T08:00:00+00:00","description":"Comment annuler une demande de visa UK que les voyageurs ont soumise : \u00e9tapes de retrait, quels frais sont remboursables, et comment faire une nouvelle demande propre en 2026.","breadcrumb":{"@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#primaryimage","url":"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061992.jpg","contentUrl":"https:\/\/visaeta.uk\/wp-content\/uploads\/2026\/07\/visaeta-8061992.jpg","width":940,"height":627,"caption":"Cancel visa application UK concept with passport, laptop and paperwork"},{"@type":"BreadcrumbList","@id":"https:\/\/visaeta.uk\/blog\/uk-eta-vs-visa\/cancel-visa-application-uk-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/visaeta.uk\/"},{"@type":"ListItem","position":2,"name":"How to Cancel or Withdraw a UK Visa Application (2026)"}]},{"@type":"WebSite","@id":"https:\/\/visaeta.uk\/#website","url":"https:\/\/visaeta.uk\/","name":"VISA ETA POUR LA GRANDE-BRETAGNE - UK","description":"","publisher":{"@id":"https:\/\/visaeta.uk\/#organization"},"alternateName":"ETA visa to the UK","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visaeta.uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/visaeta.uk\/#organization","name":"Visa ETA Royaume-Uni","url":"https:\/\/visaeta.uk\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/visaeta.uk\/#\/schema\/logo\/image\/","url":"https:\/\/visaeta.uk\/wp-content\/uploads\/2023\/11\/cropped-ETA-UK-2.png","contentUrl":"https:\/\/visaeta.uk\/wp-content\/uploads\/2023\/11\/cropped-ETA-UK-2.png","width":269,"height":53,"caption":"ETA VISA UK"},"image":{"@id":"https:\/\/visaeta.uk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/visaeta.uk\/#\/schema\/person\/81b5965766d02d43333b31730f5fa1c3","name":"\u00c9quipe \u00e9ditoriale de VisaETA","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/77324b0d1ba9a1c5a0b04ea41b2c3f26d5e8eefd0ee6b4f256de4805c6ebd71c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/77324b0d1ba9a1c5a0b04ea41b2c3f26d5e8eefd0ee6b4f256de4805c6ebd71c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/77324b0d1ba9a1c5a0b04ea41b2c3f26d5e8eefd0ee6b4f256de4805c6ebd71c?s=96&d=mm&r=g","caption":"VisaETA Editorial Team"},"sameAs":["http:\/\/visaeta.uk"],"url":"https:\/\/visaeta.uk\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/visaeta.uk\/fr\/wp-json\/wp\/v2\/posts\/6797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaeta.uk\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaeta.uk\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaeta.uk\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visaeta.uk\/fr\/wp-json\/wp\/v2\/comments?post=6797"}],"version-history":[{"count":1,"href":"https:\/\/visaeta.uk\/fr\/wp-json\/wp\/v2\/posts\/6797\/revisions"}],"predecessor-version":[{"id":6966,"href":"https:\/\/visaeta.uk\/fr\/wp-json\/wp\/v2\/posts\/6797\/revisions\/6966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaeta.uk\/fr\/wp-json\/wp\/v2\/media\/6796"}],"wp:attachment":[{"href":"https:\/\/visaeta.uk\/fr\/wp-json\/wp\/v2\/media?parent=6797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaeta.uk\/fr\/wp-json\/wp\/v2\/categories?post=6797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaeta.uk\/fr\/wp-json\/wp\/v2\/tags?post=6797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}